{"id":7694,"date":"2018-12-21T10:44:37","date_gmt":"2018-12-21T08:44:37","guid":{"rendered":"http:\/\/www.moia.cat\/web\/?p=7694"},"modified":"2018-12-21T10:44:37","modified_gmt":"2018-12-21T08:44:37","slug":"les-coves-del-toll-protagonistes-dels-pastorets-de-folch-i-torres-el-25-i-30-de-desembre-de-2018-a-les-faixes","status":"publish","type":"post","link":"https:\/\/www.moia.cat\/web\/les-coves-del-toll-protagonistes-dels-pastorets-de-folch-i-torres-el-25-i-30-de-desembre-de-2018-a-les-faixes\/","title":{"rendered":"Les Coves del Toll protagonistes dels Pastorets de Folch i Torres el 25 i 30 de desembre de 2018 a les Faixes"},"content":{"rendered":"<p>Les Coves del Toll seran protagonistes dels Pastorets de Folch i Torres que es representaran a L\u2019Espai Cultural de les Faixes els propers dies 25 i 30 de desembre de 2018 a les set de la tarda.<\/p>\n<p>Aquest pastorets aportaran algunes novetats destacades, i entre ells \u00e9s que les Coves del Toll seran protagonistes dels principals escenaris on transc\u00f3rrer l\u2019obra.<\/p>\n<p>Despr\u00e9s de 22 anys sense pastorets de Folch i Torres en format teatral gran a Moi\u00e0, torna aquest cl\u00e0ssic al nostre poble. Segons els directors de l\u2019obra Albert Sala i Elvira Permanyer, la darrera vegada que es van fer aquesta versi\u00f3 cl\u00e0ssica dels pastorets fou l\u2019any 1996 al \u201cCasal\u201d.<\/p>\n<p><a href=\"http:\/\/www.moia.cat\/wp-content\/uploads\/2018\/12\/Cartell-pastorets-001.jpg\" rel='prettyPhoto'><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-7432 appear-display\" src=\"http:\/\/www.moia.cat\/wp-content\/uploads\/2018\/12\/Cartell-pastorets-001.jpg\" sizes=\"(max-width: 1684px) 100vw, 1684px\" srcset=\"http:\/\/www.moia.cat\/wp-content\/uploads\/2018\/12\/Cartell-pastorets-001.jpg 1684w, http:\/\/www.moia.cat\/wp-content\/uploads\/2018\/12\/Cartell-pastorets-001-212x300.jpg 212w, http:\/\/www.moia.cat\/wp-content\/uploads\/2018\/12\/Cartell-pastorets-001-768x1086.jpg 768w, http:\/\/www.moia.cat\/wp-content\/uploads\/2018\/12\/Cartell-pastorets-001-724x1024.jpg 724w\" alt=\"\" width=\"1684\" height=\"2381\" \/><\/a>Aquesta \u00e9s una tradici\u00f3 arrelada a Moi\u00e0, ja que segons ens comenten els directors la primera vegada que es van representar els Pastorets de Folch i Torres a Moi\u00e0 fou l\u2019any 1921, o sigui aviat en far\u00e0 el centenari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Coves del Toll seran protagonistes dels Pastorets de Folch i Torres que es representaran a L\u2019Espai Cultural de les Faixes els propers dies 25 i 30 de desembre de 2018 a les set de la tarda. Aquest pastorets aportaran algunes novetats destacades, i entre ells \u00e9s que les Coves del Toll seran protagonistes dels principals escenaris on transc\u00f3rrer l\u2019obra. Despr\u00e9s de 22 anys sense pastorets de Folch i Torres en format teatral gran a Moi\u00e0, torna aquest cl\u00e0ssic al nostre poble. Segons els directors de l\u2019obra Albert Sala i Elvira Permanyer, la darrera vegada que es van fer aquesta versi\u00f3 cl\u00e0ssica dels pastorets fou l\u2019any 1996 al \u201cCasal\u201d. Aquesta \u00e9s una tradici\u00f3 arrelada a Moi\u00e0, ja que segons ens comenten els directors la primera vegada que es van representar els Pastorets de Folch i Torres a Moi\u00e0 fou l\u2019any 1921, o sigui aviat en far\u00e0 el centenari.<\/p>\n","protected":false},"author":9,"featured_media":7695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-7694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-dactivitats"],"rttpg_featured_image_url":{"full":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"landscape":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"portraits":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"thumbnail":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-150x150.jpg",150,150,true],"medium":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-300x140.jpg",300,140,true],"large":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"1536x1536":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"2048x2048":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"mm_thumb":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-296x270.jpg",296,270,true],"cityofwp_slider":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"cityofwp_large":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves.jpg",750,350,false],"cityofwp_small":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-280x260.jpg",280,260,true],"cityofwp_small2":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-411x180.jpg",411,180,true],"cityofwp_tabs":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-60x60.jpg",60,60,true],"sow-carousel-default":["https:\/\/www.moia.cat\/web\/wp-content\/uploads\/2018\/12\/coves-272x182.jpg",272,182,true]},"rttpg_author":{"display_name":"Ajuntament de Moi\u00e0","author_link":"https:\/\/www.moia.cat\/web\/author\/ajuntament\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.moia.cat\/web\/category\/agenda-dactivitats\/\" rel=\"category tag\">Agenda d'activitats<\/a>","rttpg_excerpt":"Les Coves del Toll seran protagonistes dels Pastorets de Folch i Torres que es representaran a L\u2019Espai Cultural de les Faixes els propers dies 25 i 30 de desembre de 2018 a les set de la tarda. Aquest pastorets aportaran algunes novetats destacades, i entre ells \u00e9s que les Coves del Toll seran protagonistes dels&hellip;","_links":{"self":[{"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/posts\/7694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/comments?post=7694"}],"version-history":[{"count":1,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/posts\/7694\/revisions"}],"predecessor-version":[{"id":7696,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/posts\/7694\/revisions\/7696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/media\/7695"}],"wp:attachment":[{"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/media?parent=7694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/categories?post=7694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moia.cat\/web\/wp-json\/wp\/v2\/tags?post=7694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}